{"id":8465,"count":1,"description":"","link":"https:\/\/ernestojerardo.com\/index.php\/tag\/hugo-menendez\/","name":"Hugo Men\u00e9ndez","slug":"hugo-menendez","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ernestojerardo.com\/index.php\/wp-json\/wp\/v2\/tags\/8465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ernestojerardo.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ernestojerardo.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ernestojerardo.com\/index.php\/wp-json\/wp\/v2\/posts?tags=8465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}