{"id":8405,"count":1,"description":"","link":"https:\/\/ernestojerardo.com\/index.php\/tag\/ultimas-predicciones\/","name":"\u00daltimas Predicciones","slug":"ultimas-predicciones","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ernestojerardo.com\/index.php\/wp-json\/wp\/v2\/tags\/8405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ernestojerardo.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ernestojerardo.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ernestojerardo.com\/index.php\/wp-json\/wp\/v2\/posts?tags=8405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}