{"id":236969,"date":"2026-07-13T13:04:00","date_gmt":"2026-07-13T18:04:00","guid":{"rendered":"https:\/\/ernestojerardo.com\/?p=236969"},"modified":"2026-07-14T17:07:37","modified_gmt":"2026-07-14T22:07:37","slug":"luciana-fuster-confirma-que-encontro-al-hombre-de-su-vida","status":"publish","type":"post","link":"https:\/\/ernestojerardo.com\/index.php\/2026\/07\/13\/luciana-fuster-confirma-que-encontro-al-hombre-de-su-vida\/","title":{"rendered":"Luciana Fuster confirma que encontr\u00f3 al hombre de su vida"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00abS\u00ed. Estoy bien feliz\u00bb. Con esas palabras, Luciana Fuster confirm\u00f3 en exclusiva para \u201cArriba Mi Gente\u201d que ha encontrado al hombre de su vida en el productor colombiano Juan Morelli. \u00abEstamos contentos, viviendo el d\u00eda a d\u00eda, acompa\u00f1\u00e1ndonos en todo lo que se puede. \u00bfEs dif\u00edcil llevar una relaci\u00f3n a distancia? \u00bfSabes qu\u00e9? No se me est\u00e1 haciendo dif\u00edcil. La comunicaci\u00f3n es todo, tenemos muchos momentos en el d\u00eda en los que hablamos, nos contamos todo. Es bonito saber que se puede construir y mantener algo a distancia. Todo va fluyendo\u00bb, confes\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ex Miss Grand International tambi\u00e9n cont\u00f3 que decidi\u00f3 alejarse un tiempo de los reflectores para enfocarse en ella misma. \u00abHace mucho tiempo que no hablo de m\u00ed, de mis proyectos, de mi vida. He estado muy metida en m\u00ed, muy enfocada en lo que estaba construyendo. Me he estado reservando muchas cosas, guard\u00e1ndome, no contando tanto de lo que hago y siento que as\u00ed estoy tranquila\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, record\u00f3 que la experiencia de vivir sola en Tailandia tras ganar el Miss Grand International marc\u00f3 un antes y un despu\u00e9s en su vida. \u00abSiento que me cambi\u00f3 mucho a nivel madurez, a nivel ser m\u00e1s organizada, aprender a ser independiente. Estaba lejos de mi familia, fue dif\u00edcil, pero en un momento mi chip cambi\u00f3 y dije: &#8216;Este es mi momento, yo contra el mundo&#8217;. Fue dif\u00edcil, pero se logr\u00f3\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora, Luciana tambi\u00e9n apuesta por una nueva etapa profesional con la inauguraci\u00f3n de su propia academia Luciana Fuster Academy. \u00abSiempre es muy importante conocerte, autodescubrirte y saber cu\u00e1l es tu mejor \u00e1ngulo. Me parece muy importante haber llamado profesores especializados en cada \u00e1rea\u00bb, se\u00f1al\u00f3 sobre este proyecto, donde se dictan cursos de pasarela, fotopose, oratoria, maquillaje e imagen personal. \u00a1No te pierdas \u201cArriba Mi Gente\u201d, de lunes a viernes a las 9 a.m. por Latina!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abS\u00ed. Estoy bien feliz\u00bb. Con esas palabras, Luciana Fuster confirm\u00f3 en exclusiva para \u201cArriba Mi Gente\u201d que ha encontrado al hombre de su vida en el productor colombiano Juan Morelli. \u00abEstamos contentos, viviendo el d\u00eda a d\u00eda, acompa\u00f1\u00e1ndonos en todo lo que se puede. \u00bfEs dif\u00edcil llevar una relaci\u00f3n a distancia? \u00bfSabes qu\u00e9? No se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":236970,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[90],"tags":[7818,689,7474,8202,8201],"class_list":["post-236969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-television","tag-arriba-mi-gente","tag-confirma","tag-encontro","tag-hombre-de-su-vida","tag-luciana-fuster"],"_links":{"self":[{"href":"https:\/\/ernestojerardo.com\/index.php\/wp-json\/wp\/v2\/posts\/236969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ernestojerardo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ernestojerardo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ernestojerardo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ernestojerardo.com\/index.php\/wp-json\/wp\/v2\/comments?post=236969"}],"version-history":[{"count":1,"href":"https:\/\/ernestojerardo.com\/index.php\/wp-json\/wp\/v2\/posts\/236969\/revisions"}],"predecessor-version":[{"id":236971,"href":"https:\/\/ernestojerardo.com\/index.php\/wp-json\/wp\/v2\/posts\/236969\/revisions\/236971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ernestojerardo.com\/index.php\/wp-json\/wp\/v2\/media\/236970"}],"wp:attachment":[{"href":"https:\/\/ernestojerardo.com\/index.php\/wp-json\/wp\/v2\/media?parent=236969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ernestojerardo.com\/index.php\/wp-json\/wp\/v2\/categories?post=236969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ernestojerardo.com\/index.php\/wp-json\/wp\/v2\/tags?post=236969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}